{"id":45,"date":"2021-01-30T08:36:46","date_gmt":"2021-01-30T11:36:46","guid":{"rendered":"https:\/\/estudobiblico.org\/gl\/?p=45"},"modified":"2021-01-30T08:36:46","modified_gmt":"2021-01-30T11:36:46","slug":"pais-fillos-e-igrexa","status":"publish","type":"post","link":"https:\/\/estudobiblico.org\/gl\/pais-fillos-e-igrexa\/","title":{"rendered":"Pais, fillos e igrexa"},"content":{"rendered":"<p>Como membros da sociedade, os pais cristi\u00e1ns necesitan educar aos seus fillos e non deben deixar ese cargo \u00e1 igrexa nin a ningunha outra instituci\u00f3n.<\/p>\n<hr \/>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/estudobiblico.org\/gl\/pais-fillos-e-igrexa\/#Pais_fillos_e_igrexa\" >Pais, fillos e igrexa<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/estudobiblico.org\/gl\/pais-fillos-e-igrexa\/#Introducion\" >Introduci\u00f3n<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/estudobiblico.org\/gl\/pais-fillos-e-igrexa\/#Fillo_dun_crente_ten_que_nacer_de_novo\" >Fillo dun crente ten que nacer de novo<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/estudobiblico.org\/gl\/pais-fillos-e-igrexa\/#A_Igrexa_e_o_corpo_de_Cristo\" >A Igrexa \u00e9 o corpo de Cristo\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/estudobiblico.org\/gl\/pais-fillos-e-igrexa\/#A_responsabilidade_de_educar\" >A responsabilidade de educar<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/estudobiblico.org\/gl\/pais-fillos-e-igrexa\/#Cando_comezar_a_educar\" >Cando comezar a educar?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/estudobiblico.org\/gl\/pais-fillos-e-igrexa\/#Os_nenos_e_a_sociedade\" >Os nenos e a sociedade<\/a><\/li><\/ul><\/nav><\/div>\n<h2 style=\"text-align: center\"><span class=\"ez-toc-section\" id=\"Pais_fillos_e_igrexa\"><\/span><span style=\"text-decoration: underline\">Pais, fillos e igrexa<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Introducion\"><\/span><span style=\"text-decoration: underline\"><strong>Introduci\u00f3n<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Que podo facer para manter ao meu fillo na igrexa? Esta \u00e9 unha pregunta feita por moitos pais cristi\u00e1ns.<\/p>\n<p>Aqueles con nenos pequenos queren f\u00f3rmulas para evitar que os seus fillos se afasten da igrexa e os que te\u00f1en nenos grandes, que se distanciaron da igrexa, queren que Deus faga un milagre.<\/p>\n<p>Que facer?<\/p>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Fillo_dun_crente_ten_que_nacer_de_novo\"><\/span><span style=\"text-decoration: underline\"><strong>Fillo dun crente ten que nacer de novo <\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Primeiro de todo, todo cristi\u00e1n debe ser consciente de que &#8220;os fillos da carne non son fillos de Deus&#8221;. Como? O meu fillo, nacido nun lugar de nacemento evanx\u00e9lico e \/ ou protestante, non \u00e9 fillo de Deus?<\/p>\n<p>Agora, se &#8220;fillo dun crente fose fillo de Deus&#8221;, teriamos que estar de acordo en que todos os descendentes de Abraham tam\u00e9n son fillos de Deus, con todo, isto non \u00e9 o que ensina a Biblia.<\/p>\n<p>O ap\u00f3stolo Paulo, escribindo aos cristi\u00e1ns de Roma, deixou claro que ser descendente da carne de Abraham non \u00e9 o que outorga a filiaci\u00f3n divina.<strong> \u201cNon faltou a palabra de Deus, porque non todos os que son de Israel son israelitas; Non porque sexan descendentes de Abraham, son todos nenos \u201d<\/strong>(Rom. 9: 6 -7).<strong> &#8220;&#8230; Non son fillos de Deus os fillos da carne, sen\u00f3n que os fillos da promesa son contados como descendentes&#8221;<\/strong> (Rom. 9: 8). Agora ben, se os fillos de Abraham non son fillos de Deus, tam\u00e9n se deduce que o fillo dun crente non \u00e9 fillo de Deus.<\/p>\n<p>Polo tanto, calquera que queira alcanzar a filiaci\u00f3n divina debe ter a mesma fe que o crente Abraham, \u00e9 dicir, para que o fillo dun cristi\u00e1n sexa fillo de Deus, debe necesariamente crer do mesmo xeito que o pai creu na mensaxe do evanxeo.<\/p>\n<p style=\"padding-left: 40px\"><strong>&#8220;Sabe, ent\u00f3n, que os que son de fe son fillos de Abraham&#8221;<\/strong> (Gal. 3: 7).<\/p>\n<p>S\u00f3 os que se xeran a trav\u00e9s da semente incorruptible, que \u00e9 a palabra de Deus, son fillos de Deus, \u00e9 dicir, os fillos dos cristi\u00e1ns non son necesariamente fillos de Deus.<\/p>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"A_Igrexa_e_o_corpo_de_Cristo\"><\/span><span style=\"text-decoration: underline\">A Igrexa \u00e9 o corpo de Cristo\u00a0<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>En segundo lugar, todos os cristi\u00e1ns deben ser conscientes de que o corpo de Cristo, que tam\u00e9n se chama igrexa, non se pode confundir con instituci\u00f3ns humanas, como a familia e a igrexa. Formar parte dunha instituci\u00f3n humana non fai que o home pertenza ao corpo de Cristo, \u00e9 dicir, salvado.<\/p>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"A_responsabilidade_de_educar\"><\/span><span style=\"text-decoration: underline\"><strong>A <\/strong><strong>responsabilidade de educar<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Como membros da sociedade, os pais cristi\u00e1ns necesitan educar aos seus fillos e non deber\u00edan deixar ese cargo \u00e1 igrexa nin a ningunha outra instituci\u00f3n. Tal tarefa \u00e9 exclusiva dos pais. Se os pais est\u00e1n ausentes, esta tarefa deber\u00eda transferirse a outra persoa que desempe\u00f1e este papel: av\u00f3s, t\u00edos ou, como \u00faltimo recurso, unha instituci\u00f3n establecida pola sociedade (orfanato).<\/p>\n<p>Por que non se pode delegar a misi\u00f3n de criar fillos? Porque dentro da normalidade, os pais son as persoas que te\u00f1en a mellor e maior confianza nos primeiros anos da vida dun individuo. Partindo desta relaci\u00f3n de confianza, a instituci\u00f3n familiar conv\u00e9rtese nun laboratorio onde se realizan todas as probas para producir un cidad\u00e1n responsable.<\/p>\n<p>\u00c9 dentro da familia cando se aprende o que \u00e9 autoridade e responsabilidade. As relaci\u00f3ns humanas apr\u00e9ndense e desenv\u00f3lvense dentro da familia, como a fraternidade, a amizade, a confianza, o respecto, o cari\u00f1o, etc.<\/p>\n<p>Como os pais te\u00f1en a mellor e m\u00e1is confiada relaci\u00f3n, tam\u00e9n son os mellores para presentar o evanxeo de Cristo aos nenos durante o proceso educativo. Polo tanto, \u00e9 saudable que os pais non presenten aos seus fillos cun Deus vingativo e rancoroso. Frases como: \u201c- Non fagas isto porque a pap\u00e1 non lle gusta! Ou, se fas isto, Deus castiga!\u201d, Non reflicte a verdade do evanxeo e causa un enorme dano \u00e1 comprensi\u00f3n do neno.<\/p>\n<p>A relaci\u00f3n que o evanxeo establece entre Deus e os homes est\u00e1 guiada pola confianza e a fidelidade. \u00bf\u00c9 posible confiar en algu\u00e9n que \u00e9 rancoroso e vingativo? Non! Agora ben, como \u00e9 posible que un mozo conf\u00ede en Deus se o que se lle presentou non coincide coa verdade do evanxeo?<\/p>\n<p>Os pais te\u00f1en que demostrarlles aos seus fillos que alg\u00fans comportamentos non se toleran porque o pai e a nai efectivamente desaproban. Que esas actitudes estean efectivamente prohibidas polo pai e a nai. Que ese comportamento \u00e9 prexudicial e toda a sociedade tam\u00e9n o desaproba.<\/p>\n<p>Non presente ao seu fillo un Deus resentido e nervioso que estea listo para castigalo por calquera mala conduta. Tal comportamento por parte dos pais demostra claramente que est\u00e1n eludindo a s\u00faa responsabilidade como educador.<\/p>\n<p>Educar aos nenos establecendo unha relaci\u00f3n de medo, ter a Deus, a igrexa, o pastor, o cura, o demo, o inferno, a polic\u00eda, o boi de cara negra, etc., como verdugos ou castigo, acaba producindo homes que non fan. respecta as instituci\u00f3ns e despreza a quen exerce a autoridade. Este tipo de educaci\u00f3n establece o medo no canto do respecto, xa que non se establece a relaci\u00f3n de confianza. Cando o medo pasa, xa non hai ningunha raz\u00f3n para obedecer.<\/p>\n<p>Os pais que act\u00faan deste xeito cando educan aos seus fillos te\u00f1en a s\u00faa parte de culpa ao enganar aos seus fillos. A igrexa tam\u00e9n ten a s\u00faa parte, porque non nomeou aos pais como o \u00fanico e lex\u00edtimo responsable da educaci\u00f3n dos seus fillos. O Estado tam\u00e9n \u00e9 culpable, xa que asume o papel de educador, cando en realidade s\u00f3 \u00e9 un veh\u00edculo para a transmisi\u00f3n do co\u00f1ecemento.<\/p>\n<p>Se as bases da educaci\u00f3n non est\u00e1n delimitadas dentro da familia e tales conceptos aplicados e experimentados nas relaci\u00f3ns familiares, calquera outra instituci\u00f3n humana, como a igrexa e o estado, estar\u00e1 condenada ao fracaso.<\/p>\n<p>Moitos pais se dedican ao traballo, ao estudo e \u00e1 igrexa, pero non invisten tempo na educaci\u00f3n dos seus fillos. A educaci\u00f3n dos nenos ten lugar a tempo completo e non \u00e9 saudable descoidar esta vez.<\/p>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Cando_comezar_a_educar\"><\/span><span style=\"text-decoration: underline\"><strong>Cando comezar a educar?<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>A preocupaci\u00f3n polos nenos xeralmente xorde cando os pais cristi\u00e1ns senten que os seus fillos se distancian da instituci\u00f3n da igrexa. Chamamentos temerosos \u00e1 imposici\u00f3n e coacci\u00f3n, que obrigan aos nenos a ir \u00e1 igrexa. Tal actitude equiv\u00f3case a\u00ednda m\u00e1is que non ter instru\u00eddo ao neno no momento oportuno.<\/p>\n<p>Estas preguntas sorprenden a alg\u00fans pais cristi\u00e1ns porque non saben cal \u00e9 o seu papel como membro da sociedade e cal \u00e9 a s\u00faa misi\u00f3n como embaixador do evanxeo. Os pais cristi\u00e1ns non poden mesturar estas d\u00faas funci\u00f3ns.<\/p>\n<p>Os pais cristi\u00e1ns te\u00f1en d\u00faas misi\u00f3ns moi diferentes:<\/p>\n<p style=\"padding-left: 40px\">a) educar aos seus fillos para que sexan membros da sociedade e;<\/p>\n<p style=\"padding-left: 40px\">b) anunciar as marabillosas promesas do evanxeo aos nenos para que nunca se afasten da fe.<\/p>\n<p>Estas misi\u00f3ns deben realizarse desde pequenas, coidando de tratar simultaneamente coa educaci\u00f3n e formaci\u00f3n dun cidad\u00e1n, sen deixar de lado o ensino da palabra da verdade, facendo fincap\u00e9 no amor e a fidelidade de Deus.<\/p>\n<p>Dende pequeno hai que ensinarlle ao neno a respectar as autoridades e \u00e9 a trav\u00e9s dos pais que o neno ser\u00e1 exercido respecto \u00e1 submisi\u00f3n \u00e1 autoridade. A trav\u00e9s de irm\u00e1ns, av\u00f3s e t\u00edos, o neno aprender\u00e1 respecto e convivencia. Como amigos, profesores, veci\u00f1os e estra\u00f1os, o neno aprender\u00e1 relaci\u00f3ns co mundo.<\/p>\n<p>Que pasa co evanxeo? Que recomenda a Biblia? En Deuteronomio lemos o seguinte:<strong>\u00a0&#8220;E ensinaras aos teus fillos e falar\u00e1s deles sentado na t\u00faa casa, cami\u00f1ando polo cami\u00f1o, deitado e levant\u00e1ndose&#8221;<\/strong> (Deut 6: 7). Sobre o modo de vida, o neno debe ser instru\u00eddo en todo momento, \u00e9 dicir, na casa, no cami\u00f1o, \u00e1 hora de durmir e ao levantarse.<\/p>\n<p>A instruci\u00f3n das &#8220;cartas&#8221; sagradas \u00e9 responsabilidade dos pais! As escrituras non recomendan delegar tal funci\u00f3n no profesor da escola dominical, ademais, restrinxe o tempo de ensinanza sobre Cristo a unha vez por semana, por un per\u00edodo de s\u00f3 unha hora. Totalmente diferente do que recomenda a escritura: ensino diario.<\/p>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Os_nenos_e_a_sociedade\"><\/span><span style=\"text-decoration: underline\"><strong>Os nenos e a sociedade<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Os pais deben axudar aos nenos a comprender que todos deben a obediencia aos pais e \u00e1 sociedade. O env\u00edo aos pais hoxe \u00e9 un ensaio e un aprendizaxe para o env\u00edo que requirir\u00e1 a sociedade, tanto na escola como no traballo.<\/p>\n<p>Despois de ser instru\u00eddo, a\u00ednda que o mozo non quixese seguir o evanxeo de Cristo, teremos un cidad\u00e1n comprometido con certos valores sociais.<\/p>\n<p>Un dos problemas pertinentes na educaci\u00f3n dos fillos dos cristi\u00e1ns na actualidade \u00e9 mesturar a educaci\u00f3n familiar coa igrexa. Delegar na igrexa a responsabilidade de transmitir valores socioculturais \u00e9 un gran erro. Cando o mozo medra e est\u00e1 decepcionado con certas persoas dentro da instituci\u00f3n, acaba afast\u00e1ndose da pertenza \u00e1 comunidade \u00e1 que asistiu e, ao mesmo tempo, reb\u00e9lase contra calquera tipo de valor social.<\/p>\n<p>Cando os pais son conscientes de que non xeran fillos para Deus, apl\u00edcanse m\u00e1is \u00e1 educaci\u00f3n e \u00e1 evanxelizaci\u00f3n dos nenos. Tampouco se desesperan cando ven que os seus brotes non est\u00e1n de humor para ir \u00e1 igrexa. Non se sentir\u00e1n culpables nin responsables dos seus fillos cando non aborden alg\u00fans problemas institucionais.<\/p>\n<p>Non obstante, \u00e9 necesario educar aos nenos ensinando a palabra de Deus sen esquecer transmitir e inculcar valores sociais. A educaci\u00f3n incl\u00fae conversa, xogo, rega\u00f1as, avisos, etc. Permitir aos nenos experimentar todas as etapas da vida, desde a infancia, a adolescencia e a mocidade.<\/p>\n<p>Pero, que facer cando os nenos se afastan da igrexa? En primeiro lugar, \u00e9 necesario distinguir se os nenos se afastaron do evanxeo ou se distanciaron dunha instituci\u00f3n concreta.<\/p>\n<p>Ignorar os principios elementais do evanxeo leva aos pais a confundir o que significa ser fillo de Deus coa pertenza a unha igrexa en particular. Se un neno xa non \u00e9 un asiduo na igrexa, non se lle debe etiquetar como perdido, nin que cami\u00f1a cara ao inferno, etc.<\/p>\n<p>Se unha persoa profesa a verdade do evanxeo como din as escrituras, significa que non \u00e9 un perdido, sen\u00f3n que debe ser alertado s\u00f3 da necesidade de congregarse. Pode ser necesario que os pais investiguen por que os seus fillos deixan o costume de reunirse con outros cristi\u00e1ns.<\/p>\n<p>Agora ben, se o fillo non profesa a verdade do evanxeo e segue congreg\u00e1ndose por costume, a s\u00faa condici\u00f3n ante Deus \u00e9 preocupante. Que sabe sobre o evanxeo? Profesa a fe do evanxeo? Se a resposta \u00e9 negativa, \u00e9 necesario anunciar a verdade do evanxeo para que poida crer e salvarse, e non s\u00f3 un eclesi\u00e1stico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como membros da sociedade, os pais cristi\u00e1ns necesitan educar aos seus fillos e non deben deixar ese cargo \u00e1 igrexa nin a ningunha outra instituci\u00f3n.<\/p>\n","protected":false},"author":1,"featured_media":46,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[5,9,10,19],"class_list":["post-45","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria","tag-educar","tag-fillos","tag-igrexa","tag-pais"],"acf":[],"_links":{"self":[{"href":"https:\/\/estudobiblico.org\/gl\/wp-json\/wp\/v2\/posts\/45","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/estudobiblico.org\/gl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/estudobiblico.org\/gl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/estudobiblico.org\/gl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/estudobiblico.org\/gl\/wp-json\/wp\/v2\/comments?post=45"}],"version-history":[{"count":0,"href":"https:\/\/estudobiblico.org\/gl\/wp-json\/wp\/v2\/posts\/45\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/estudobiblico.org\/gl\/wp-json\/wp\/v2\/media\/46"}],"wp:attachment":[{"href":"https:\/\/estudobiblico.org\/gl\/wp-json\/wp\/v2\/media?parent=45"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/estudobiblico.org\/gl\/wp-json\/wp\/v2\/categories?post=45"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/estudobiblico.org\/gl\/wp-json\/wp\/v2\/tags?post=45"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}