{"id":109,"date":"2019-09-28T10:39:15","date_gmt":"2019-09-28T13:39:15","guid":{"rendered":"https:\/\/estudobiblico.org\/it\/?p=109"},"modified":"2019-09-28T10:39:15","modified_gmt":"2019-09-28T13:39:15","slug":"non-ce-condanna-per-coloro-che-sono-in-cristo","status":"publish","type":"post","link":"https:\/\/estudobiblico.org\/it\/non-ce-condanna-per-coloro-che-sono-in-cristo\/","title":{"rendered":"Non c&#8217;\u00e8 condanna per coloro che sono in Cristo"},"content":{"rendered":"<p>Entrambi i versetti hanno contrappunti: la &#8220;novit\u00e0 della mente&#8221; contrasta la &#8220;vecchiaia della lettera&#8221;, cos\u00ec come la &#8220;comprensione&#8221; contrasta la &#8220;carne&#8221;.<\/p>\n<hr \/>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/estudobiblico.org\/it\/non-ce-condanna-per-coloro-che-sono-in-cristo\/#Non_ce_condanna_per_coloro_che_sono_in_Cristo\" >Non c&#8217;\u00e8 condanna per coloro che sono in Cristo<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/estudobiblico.org\/it\/non-ce-condanna-per-coloro-che-sono-in-cristo\/#Introduzione\" >Introduzione<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/estudobiblico.org\/it\/non-ce-condanna-per-coloro-che-sono-in-cristo\/#Nessuna_Convinzione\" >Nessuna Convinzione<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/estudobiblico.org\/it\/non-ce-condanna-per-coloro-che-sono-in-cristo\/#Nuova_Creatura\" >Nuova Creatura<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/estudobiblico.org\/it\/non-ce-condanna-per-coloro-che-sono-in-cristo\/#Carne_Contro_Spirito\" >Carne Contro Spirito<\/a><\/li><\/ul><\/nav><\/div>\n<h2 style=\"text-align: center\"><span class=\"ez-toc-section\" id=\"Non_ce_condanna_per_coloro_che_sono_in_Cristo\"><\/span><span style=\"text-decoration: underline\">Non c&#8217;\u00e8 condanna per coloro che sono in Cristo<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"color: #0000ff\">&#8220;Quindi ora non vi \u00e8 alcuna condanna per coloro che sono in Cristo Ges\u00f9, che camminano non secondo la carne, ma secondo lo Spirito&#8221;<\/span> (Romani 8: 1).<\/p>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Introduzione\"><\/span><strong><u>Introduzione<\/u><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Prima di continuare l&#8217;analisi del capitolo 8, dall&#8217;epistola ai romani, confronta questi due versetti:<\/p>\n<p style=\"padding-left: 40px\"><span style=\"color: #0000ff\">&#8220;Ma ora siamo liberi dalla legge, poich\u00e9 moriamo per ci\u00f2 in cui eravamo tenuti, per servire nella novit\u00e0 della mente, non nella vecchiaia della lettera&#8221;<\/span> (Romani 7: 6);<\/p>\n<p style=\"padding-left: 40px\"><span style=\"color: #0000ff\">\u201cRingrazio Dio attraverso Ges\u00f9 Cristo, nostro Signore. Perci\u00f2 io stesso, comprendendo, servo la legge di Dio, ma con la carne la legge del peccato\u201d<\/span> (Romani 7:25).<\/p>\n<p>Qual \u00e8 il motivo per cui l&#8217;apostolo Paolo rende grazie a Dio attraverso Cristo Ges\u00f9? Era libero dalla legge (ora siamo liberi dalla legge) da quando era morto per ci\u00f2 che \u00e8 stato trattenuto: la legge.<\/p>\n<p>Qual era lo scopo dell&#8217;apostolo Paolo di essere morto per ci\u00f2 che fu trattenuto? La risposta \u00e8 chiara: per servire Dio nella novit\u00e0 dello spirito (vangelo), cosa impossibile attraverso la vecchiaia della lettera (legge).<\/p>\n<p>L&#8217;apostolo Paolo dichiar\u00f2 categoricamente che i cristiani erano ora liberi dalla legge, poich\u00e9 erano morti per essa, e conclude che la libert\u00e0 raggiunta come conseguenza della morte per legge ha un solo scopo: servire Dio nella novit\u00e0 della mente, poich\u00e9, attraverso la legge di Mos\u00e8 era impossibile servire Dio (Romani 8.7).<\/p>\n<p>Entrambi i versetti hanno contrappunti: la &#8220;novit\u00e0 della mente&#8221; contrasta la &#8220;vecchiaia della lettera&#8221;, cos\u00ec come la &#8220;comprensione&#8221; contrasta la &#8220;carne&#8221;. L&#8217;opposizione &#8220;vangelo&#8221; contro &#8220;legge&#8221; \u00e8 chiaro, ma l&#8217;opposizione &#8220;comprensione&#8221; contro &#8220;carne&#8221; \u00e8 molto sottile, il che porta a una lettura errata della proposta paolina.<\/p>\n<p>Il termine greco tradotto &#8220;comprensione&#8221; \u00e8 \u03bd\u03bf\u03c5\u03c2 <sup><a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a><\/sup> (nous), probabilmente derivato dalla radice del verbo \u03b3\u03b9\u03bd\u03c9\u03c3\u03ba\u03c9 (ginosko). Nel stabilire il contrappunto &#8220;comprensione&#8221; contro &#8220;carne&#8221;, siamo costretti a considerare ci\u00f2 che fu detto in seguito dall&#8217;apostolo Paolo, che gli ebrei servirono Dio senza capire (Romani 10.2), perch\u00e9 la Legge, i Salmi e i profeti erano enfatico:<\/p>\n<p style=\"padding-left: 40px\"><span style=\"color: #0000ff\">&#8220;Poich\u00e9 mancano di consigli e comprendono in essi&#8221;.<\/span> (Deuteronomio 32:28);<\/p>\n<p style=\"padding-left: 40px\"><span style=\"color: #0000ff\">\u201cPertanto il mio popolo sar\u00e0 preso prigioniero per mancanza di comprensione; e i loro nobili avranno fame e la loro moltitudine avr\u00e0 sete\u201d<\/span> (Isaia 5:13);<\/p>\n<p style=\"padding-left: 40px\"><span style=\"color: #0000ff\">\u201cDio guard\u00f2 dal cielo i figli degli uomini, per vedere se ce n&#8217;era uno che capiva e cercava Dio. Si sono tutti messi da parte e insieme diventano sporchi. nessuno fa del bene, no, nemmeno uno. Non sanno chi lavora nell&#8217;iniquit\u00e0, chi mangia la mia gente come se mangiasse il pane? Non hanno invocato Dio \u201d.<\/span> (Salmo 53: 2-4);<\/p>\n<p style=\"padding-left: 40px\"><span style=\"color: #0000ff\">\u201cIl timore dell&#8217;Eterno \u00e8 l&#8217;inizio della saggezza; la buona comprensione ha tutti quelli che obbediscono ai suoi comandamenti; la sua lode dura per sempre \u201d<\/span> (Salmo 111: 10).<\/p>\n<p>L&#8217;apostolo Paolo rende grazie a Dio nel versetto 25 perch\u00e9 \u00e8 morto per la legge e ora era libero. Cosa significa servire nella &#8220;novit\u00e0 della mente&#8221;?<\/p>\n<p><a href=\"https:\/\/estudobiblico.org\/it\/chosen-generation\/\">Libert\u00e0 di servire la volont\u00e0<\/a> (legge <a href=\"#_ftn2\" name=\"_ftnref2\"><sup>[2]<\/sup><\/a>) di Dio con comprensione, poich\u00e9 con la carne solo la legge del peccato pu\u00f2 essere servita.<\/p>\n<p style=\"padding-left: 40px\"><span style=\"color: #0000ff\">\u201cPerch\u00e9 questo \u00e8 il patto che far\u00f2 con la casa d&#8217;Israele dopo quei giorni, dice il Signore; Metter\u00f2 le mie leggi nella sua comprensione e le scriver\u00f2 nel suo cuore; E sar\u00f2 il loro Dio, e saranno il mio popolo\u201d <\/span>(Ebrei 8:10).<\/p>\n<p>In entrambi i versetti, l&#8217;apostolo Paolo usa il verbo &#8220;servire&#8221; e sopprime lo stesso verbo nella parte finale del versetto:<\/p>\n<p style=\"padding-left: 40px\"><span style=\"color: #0000ff\">&#8220;&#8230; Che possiamo servire nella novit\u00e0 della mente e non (servire) nella vecchiaia della lettera&#8221; <\/span>(Romani 7: 6);<\/p>\n<p style=\"padding-left: 40px\"><span style=\"color: #0000ff\">&#8220;&#8230; Con comprensione servo la legge di Dio, ma con carne (servo) la legge del peccato&#8221;<\/span> (Romani 7:25).<\/p>\n<p>Attraverso questa analisi \u00e8 facile diagnosticare che, a causa di fraintendimenti, cio\u00e8 senza considerare il possibile uso di determinate risorse letterarie, come figure di stile, sorgono numerosi equivoci.<\/p>\n<p>Un chiaro esempio di risorse rilevanti per la scrittura si trova nei versetti che abbiamo appena confrontato, dove abbiamo una delle figure linguistiche (Brasile), <strong>o figure di stile \/ figure retoriche (Portogallo)<\/strong>.<\/p>\n<p style=\"padding-left: 40px\"><span style=\"color: #0000ff\">&#8220;Il linguaggio figurato sono strategie letterarie che lo scrittore pu\u00f2 applicare al testo per ottenere un effetto definito sull&#8217;interpretazione. Sono forme di espressione pi\u00f9 localizzate rispetto alle funzioni linguistiche, che sono caratteristiche globali del testo. Possono riguardare aspetti semantici, fonologici o sintattici delle parole interessate.&#8221;<\/span> Wikipedia&#8221;.<\/p>\n<p>Quale risorsa ha usato l&#8217;apostolo Paolo nei versetti sopra? Usa una figura di stile chiamata ellisse, che \u00e8:<\/p>\n<p style=\"padding-left: 40px\"><em><span style=\"color: #800080\">\u201cEllisse \u00e8 una soppressione di una parola facilmente comprensibile. \u00c8 l&#8217;omissione intenzionale di un termine facilmente identificabile dal contesto o dagli elementi grammaticali presenti nella frase. Questa omissione rende il testo conciso ed elegante.\u201d <\/span><\/em>Wikipedia.<\/p>\n<p>Non considerare i principi elementari dell&#8217;interpretazione del testo distorce l&#8217;idea che lo scrittore cerca di trasmettere, portando a errori dottrinali.<\/p>\n<p>Ora, se uno non riesce a considerare elementi pertinenti alla semantica, \u00e8 pernicioso, che si direbbe che si trascurano elementi pertinenti alla retorica (l&#8217;arte del buon linguaggio), poich\u00e9 l&#8217;apostolo Paolo era un uomo che era ben versato nella cultura del tempo.<\/p>\n<p>Analizzando l&#8217;esposizione dell&#8217;apostolo Paolo, si pu\u00f2 vedere che cerca di rendere il suo interlocutore, attraverso i suoi ragionamenti, convincersi che il mittente ha ragione.<\/p>\n<p>La retorica come tecnica di esposizione non ha lo scopo di distinguere ci\u00f2 che \u00e8 vero o giusto, ma piuttosto di far giungere alla conclusione del destinatario del messaggio che l&#8217;idea implicita nel discorso rappresenta ci\u00f2 che \u00e8 vero o giusto.<\/p>\n<p>A ci\u00f2 si aggiungono diversi problemi pertinenti alla comprensione dei traduttori quando si perdono i testi sacri, poich\u00e9 i testi biblici trascritti dell&#8217;originale non avevano segni di punteggiatura, regole introdotte in ritardo.<\/p>\n<p>Sebbene analizziamo i testi biblici usando il capitolo e i riferimenti ai versi, non dobbiamo dimenticare che queste divisioni non sono state fatte dagli scrittori della Bibbia.<\/p>\n<p>Queste divisioni sono state introdotte migliaia di anni dopo la stesura dei libri originali per facilitare l&#8217;ubicazione dei passaggi e specificare, pertanto, non dovrebbero essere presi in considerazione durante la lettura e l&#8217;interpretazione del testo.<\/p>\n<p>La divisione della Bibbia in capitoli fu introdotta dal professore universitario parigino Stephen Langton nel 1227. La divisione della Bibbia in versi fu introdotta nel 1551 dallo stampatore parigino Robert Stephanus. (Le divisioni avevano lo scopo di facilitare la consultazione e le citazioni bibliche.)<\/p>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Nessuna_Convinzione\"><\/span><strong><u>Nessuna Convinzione<\/u><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"padding-left: 40px\"><span style=\"color: #0000ff\">&#8220;Quindi ora non vi \u00e8 alcuna condanna per quelli che sono in Cristo Ges\u00f9, che camminano non secondo la carne, ma secondo lo Spirito.&#8221; <\/span>(Romani 8: 1).<\/p>\n<p>Questo versetto sostiene gli argomenti che l&#8217;apostolo Paolo fece nei capitoli precedenti. Siamo in grado di comprendere la struttura della lettera indirizzata ai cristiani a Roma.<\/p>\n<p>Questo versetto introduce una conclusione, attraverso la congiunzione conclusiva, &#8220;quindi&#8221;, basata su ci\u00f2 che l&#8217;apostolo Paolo aveva espresso in precedenza.<\/p>\n<p style=\"padding-left: 40px\"><em><span style=\"color: #800080\">&#8220;Pertanto &#8211; congiunzione conclusiva equivalente a quindi, quindi, di conseguenza, di conseguenza&#8221;.\u00a0&#8220;L&#8217;uso della congiunzione &#8216;quindi&#8217; deve introdurre una conclusione basata su ci\u00f2 che \u00e8 stato detto prima &#8211; preghiera o testo precedente &#8211; quindi \u00e8 un errore iniziare un periodo, un intervento o una risposta con questa congiunzione.&#8221;<\/span><\/em><\/p>\n<p>Per comprendere la struttura della lettera, \u00e8 necessario attingere all&#8217;avverbio del tempo (ora) che l&#8217;apostolo delle genti introduce poco dopo la congiunzione conclusiva<strong>, <\/strong>&#8220;pertanto&#8221;: <span style=\"color: #0000ff\">&#8220;Pertanto ora &#8230;&#8221;<\/span> (Romani 8: 1).<\/p>\n<p>L&#8217;apostolo Paolo dimostr\u00f2 che tutti gli uomini erano sotto il peccato. (Romani 3: 1-20) e descrisse la giustizia di Dio data dal Vangelo (fede) a tutti coloro che credono (senza distinzione), e us\u00f2 l&#8217;avverbio del tempo &#8216;ora&#8217; <span style=\"color: #0000ff\">\u201cMa ora la giustizia di Dio si \u00e8 manifestata senza la legge &#8230; \u201d<\/span> (Romani 3:21).<\/p>\n<p>L&#8217;apostolo delle genti dimostra ai suoi lettori che la grazia di Dio si manifesta a tutti coloro che credono senza distinzioni, e indica attraverso l&#8217;avverbio del tempo &#8220;ora&#8221; che la giustizia di Dio \u00e8 efficace nel tempo presente.<\/p>\n<p>Il credente \u00e8 solo &#8220;ora&#8221; al tempo presente.<\/p>\n<p>\u00c8 una condizione propria di coloro che hanno creduto in Cristo, non un dono da fare solo in futuro (Romani 3:26).<\/p>\n<p>Perch\u00e9 la giustizia di Dio nel &#8220;adesso&#8221;, in questo momento, \u00e8 data a tutti senza distinzione?<\/p>\n<p>Primo, perch\u00e9 tutti hanno peccato e sono rimasti privi della gloria di Dio (Romani 3:23).<\/p>\n<p>Nota che Paolo presenta prima la grazia di Dio (Romani 3:21), quindi si riferisce alla condizione dell&#8217;umanit\u00e0 senza Cristo (Romani 3:23).<\/p>\n<p>Sulla base delle informazioni fornite nei versetti da 21 a 27 del capitolo 3 della lettera ai Romani, l&#8217;apostolo Paolo giunge alla seguente conclusione: Tutti gli uomini sono giustificati attraverso il vangelo di Cristo.<\/p>\n<p style=\"padding-left: 40px\"><span style=\"color: #0000ff\">&#8220;Pertanto concludiamo che un uomo \u00e8 giustificato dalla fede senza le opere della legge&#8221;<\/span> (Romani 3:28).<\/p>\n<p>La conclusione che l&#8217;apostolo Paolo fa nel versetto 2 del capitolo 3 lo rende presente alla persona di Abramo come esempio di un Gentile raggiunto per grazia di Dio attraverso la fede molto prima che fosse data la legge (Romani 4:10).<\/p>\n<p>Dopo aver presentato Abramo come prova completa che la grazia di Dio raggiunge anche i Gentili, l&#8217;apostolo Paolo continua dimostrando che la legge non era la causa della felicit\u00e0 raggiunta da suo padre Abramo, ma la promessa (Romani 4:13).<\/p>\n<p>Dopo aver dimostrato che sia la circoncisione che la legge non sono cause di giustificazione in Dio, l&#8217;apostolo Paolo presenta una nuova conclusione, che riprende l&#8217;argomento presentato nel capitolo 3, versetto 21: <span style=\"color: #0000ff\">\u201cPertanto, essendo giustificati dalla fede, abbiamo pace con Dio. attraverso il nostro Signore Ges\u00f9 Cristo\u201d<\/span> (Romani 5.1).<\/p>\n<p>L&#8217;apostolo Paolo aveva gi\u00e0 annunciato che la giustizia di Dio si manifestava senza la legge, secondo la testimonianza della legge e dei profeti (Romani 3:21, e conclude che la giustificazione per fede stabilisce la pace con Dio).<\/p>\n<p>Dopo aver dimostrato che i cristiani hanno raggiunto la pace con Dio, poich\u00e9 si \u00e8 riconciliato con Dio attraverso la morte di suo Figlio (Romani 5:10), l&#8217;apostolo Paolo continua dimostrando come ha avuto luogo la miseria umana della gloria di Dio (Romani 5: 12-20). ); chiarisce che \u00e8 impossibile per coloro che sono morti peccare vivere nel peccato (Romani 6: 2); che i cristiani sono liberati dalla legge (Romani 7: 7); presenta la natura della legge (Romani 7:12) e l&#8217;impossibilit\u00e0 dell&#8217;uomo carnale (Romani 7:14).<\/p>\n<p>Il passaggio dalla lettera di Paolo ai Romani tra i capitoli 6 e 7 dimostra come la giustificazione sia data dalla fede, il che porta alla seguente conclusione: abbiamo pace con Dio (Romani 5.1), perch\u00e9 siamo stati giustificati dalla sua grazia (Romani 3:24), e ora non vi \u00e8 alcuna condanna per quelli che camminano dietro a Dio (Romani 8: 1).<\/p>\n<p>La salvezza in Cristo \u00e8 per l &#8216;&#8221;ora&#8221; (tempo presente) e non per il futuro. Oggi \u00e8 il giorno della salvezza. Oggi \u00e8 il giorno pi\u00f9 accettabile (2 Corinzi 6: 2). L&#8217;uomo \u00e8 salvato oggi (presente) dalla condanna data in Eden (passato), e cos\u00ec \u00e8 giustificato oggi, ora.<\/p>\n<p>L&#8217;apostolo Paolo sottolinea che NON c&#8217;\u00e8 condanna per coloro che sono in Cristo Ges\u00f9.<\/p>\n<p>Perch\u00e9 ha scritto che non c&#8217;era condanna?<\/p>\n<p>Non sarebbe corretto: non c&#8217;\u00e8 condanna per coloro che sono in Cristo Ges\u00f9?<\/p>\n<p>Se l&#8217;apostolo dei gentili afferma che non c&#8217;\u00e8 condanna, \u00e8 perch\u00e9 era possibile pi\u00f9 di una condanna.<\/p>\n<p>Quante condanne ci sono?<\/p>\n<p>La Bibbia ci presenta due condanne:<\/p>\n<ol>\n<li>la condanna in Adamo, che ebbe luogo in Eden (passato), dove tutti gli uomini divennero peccatori, alienati (morti) da Dio (Romani 5:18);<\/li>\n<li>la condanna che sar\u00e0 data nella Grande Sala del Trono Bianco (futuro), riguardo alle opere (Apocalisse 20:12).<\/li>\n<\/ol>\n<p>Quando l&#8217;apostolo Paolo disse: non c&#8217;\u00e8 condanna per coloro che sono in Cristo, alludeva alla separazione dell&#8217;uomo e alla gloria di Dio, senza trascurare gli effetti delle opere riprovevoli dell&#8217;umanit\u00e0 senza Cristo.<\/p>\n<p>Tutti coloro che sono in Cristo, oltre ad essere liberi dalla condanna a morte a causa dell&#8217;offesa di Adamo, non appariranno davanti alla Grande Corte del Trono Bianco, ma appariranno davanti alla Corte di Cristo per essere ricompensati, dove non c&#8217;\u00e8 condanna (Romani 14:10). 2 Corinzi 5:10).<\/p>\n<p>Dato ci\u00f2 che l&#8217;apostolo Paolo annunci\u00f2: <span style=\"color: #0000ff\">&#8220;Quindi ora non c&#8217;\u00e8 condanna &#8230;&#8221;<\/span> (Romani 8: 1), \u00e8 evidente che l&#8217;uomo nuovo in Cristo \u00e8 benedetto.<\/p>\n<p style=\"padding-left: 40px\"><span style=\"color: #0000ff\">&#8220;Cos\u00ec David dichiara anche benedetto l&#8217;uomo al quale Dio imputa la giustizia senza opere, dicendo&#8221; <\/span>(Romani 4 e 8).<\/p>\n<p>Coloro che credono in Cristo hanno perdonato il loro &#8220;male&#8221;, i loro peccati sono coperti, cio\u00e8 Dio non imputa loro il peccato. Ora, se \u00e8 cos\u00ec, come \u00e8 possibile che il cristiano sia ancora un uomo &#8220;sfortunato&#8221;, &#8220;maledetto&#8221;? Se non c&#8217;\u00e8 condanna per coloro che sono in Cristo, \u00e8 improbabile che l&#8217;apostolo Paolo abbia fatto la dichiarazione &#8220;dannato uomo che sono&#8221; sulla sua nuova condizione in Cristo, ma sulla sua vecchia condizione.<\/p>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Nuova_Creatura\"><\/span><span style=\"text-decoration: underline\"><strong>Nuova Creatura<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Considerando che non vi \u00e8 alcuna condanna per coloro che sono in Cristo Ges\u00f9.<\/p>\n<p style=\"padding-left: 40px\">1-Cosa deve essere in Cristo?<\/p>\n<p style=\"padding-left: 40px\">2-Come essere in Cristo?<\/p>\n<p style=\"padding-left: 40px\">3-Qual \u00e8 la realt\u00e0 di coloro che sono in Cristo?<\/p>\n<p>Scrivendo ai cristiani di Corinto, l&#8217;apostolo Paolo fece la seguente dichiarazione:<\/p>\n<p style=\"padding-left: 40px\"><span style=\"color: #0000ff\">\u201cQuindi se qualcuno \u00e8 in Cristo, \u00e8 una nuova creatura; le cose vecchie sono passate; ecco, tutte le cose sono diventate nuove\u201d<\/span> (2 Corinzi 5:17).<\/p>\n<ol>\n<li><strong> Nuova creatura<\/strong> &#8211; Per definizione, chi \u00e8 in Cristo \u00e8 una nuova creatura;<\/li>\n<li><strong> Nuova nascita<\/strong> &#8211; \u00c8 possibile essere in Cristo solo coloro che sono rinati attraverso il seme incorruttibile, che \u00e8 la parola di Dio;<\/li>\n<li><strong> Realt\u00e0:<\/strong> le cose vecchie sono sparite e tutto \u00e8 nuovo.<\/li>\n<\/ol>\n<p>Quando leggiamo, non c&#8217;\u00e8 condanna per coloro che sono in Cristo Ges\u00f9, implica che non condanni la nuova creatura generata secondo la parola di verit\u00e0, a vivere nuova esistenza e realt\u00e0: tutto nuovo!<\/p>\n<p>Confronto:<\/p>\n<p style=\"padding-left: 40px\"><span style=\"color: #0000ff\">\u201cQuindi se qualcuno \u00e8 in Cristo, \u00e8 una nuova creatura; le cose vecchie sono passate; ecco, tutte le cose sono diventate nuove\u201d<\/span> (2 Corinzi 5:17);<\/p>\n<p style=\"padding-left: 40px\"><span style=\"color: #0000ff\">&#8220;Quindi ora non c&#8217;\u00e8 condanna per quelli che sono in Cristo Ges\u00f9, che camminano non secondo la carne, ma secondo lo Spirito&#8221; <\/span>(Romani 8: 1).<\/p>\n<p>Sulla base di questi due versetti, si conclude che &#8220;essere una nuova creatura&#8221; equivale a &#8220;essere in Cristo&#8221; e viceversa. Per coloro che sono in Cristo, non c&#8217;\u00e8 condanna. Per la nuova creatura (uno che \u00e8 in Cristo) non c&#8217;\u00e8 condanna.<\/p>\n<p>La parte b dei due versi affronta lo stesso argomento. Le &#8220;cose \u200b\u200bvecchie&#8221; che seguono si riferiscono al &#8220;camminare secondo la carne&#8221;, cos\u00ec come &#8220;camminare secondo lo spirito&#8221; si riferisce a &#8220;tutto ci\u00f2 che \u00e8 diventato nuovo&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Carne_Contro_Spirito\"><\/span><strong><u>Carne Contro Spirito<\/u><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Per continuare l&#8217;esposizione, \u00e8 innanzitutto necessario definire cosa sia &#8220;carne&#8221; e cosa sia &#8220;spirito&#8221; in questo contesto, poich\u00e9 una buona lettura e una comprensione sicura del capitolo 8 dei romani dipende da questa definizione.<\/p>\n<p>La prima volta che l&#8217;apostolo Paolo usa il termine carne era in relazione a Ges\u00f9, per dimostrare che Egli \u00e8 il seme promesso da Dio a David (2 Samuele 7:14), il Verbo si fece carne (Giovanni 1:14).<\/p>\n<p style=\"padding-left: 40px\"><span style=\"color: #0000ff\">&#8220;Riguardo a suo Figlio, che nacque dal seme di David secondo la carne&#8221;<\/span> (Romani 1: 3).<\/p>\n<p>Il termine greco &#8216;\u03c3\u03ac\u03c1\u03ba\u03b1&#8217; (sarx), tradotto come &#8216;carne&#8217;, \u00e8 stato usato per dimostrare che Ges\u00f9 Cristo appartiene al lignaggio di David, attraverso il legame di sangue che \u00e8 stato concepito dalla Vergine Maria.<\/p>\n<p>Lo stesso termine \u00e8 usato nel capitolo 2:<\/p>\n<p style=\"padding-left: 40px\"><span style=\"color: #0000ff\">&#8220;Perch\u00e9 non \u00e8 un ebreo che \u00e8 uno esternamente, n\u00e9 la circoncisione \u00e8 ci\u00f2 che \u00e8 esternamente nella carne&#8221;<\/span> (Romani 2:28).<\/p>\n<p>In questo verso, l&#8217;apostolo usa il termine per riferirsi al segno della circoncisione che gli ebrei portano a causa del segno che Dio diede ad Abramo (Genesi 17: 10-13).<\/p>\n<p style=\"padding-left: 40px\"><span style=\"color: #0000ff\">\u201cE l&#8217;uomo non circonciso, la cui carne del prepuzio non \u00e8 circoncisa, quell&#8217;anima sar\u00e0 separata dal suo popolo; Ha infranto la mia alleanza \u201d.<\/span> (Genesi 14:14).<\/p>\n<p>Inoltre, l&#8217;apostolo Paolo allude all&#8217;umanit\u00e0 attraverso il termine &#8220;carne&#8221;:<\/p>\n<p style=\"padding-left: 40px\"><span style=\"color: #0000ff\">&#8220;Pertanto nessuna carne sar\u00e0 giustificata davanti a lui dalle opere della legge, perch\u00e9 dalla legge deriva la conoscenza del peccato&#8221;<\/span> (Romani 3:20).<\/p>\n<p>Dopo aver citato i Salmi e i Profeti (Romani 3: 10-18), l&#8217;apostolo Paolo sottolinea che &#8220;nessuna carne&#8221; \u00e8 giustificata attraverso le opere della legge, cio\u00e8, attraverso le opere della legge, n\u00e9 ebrei n\u00e9 greci possono essere giustificati.<\/p>\n<p>Il prossimo uso del termine carne viene fatto in relazione a padre Abramo:<\/p>\n<p style=\"padding-left: 40px\"><span style=\"color: #0000ff\">&#8220;Che dire allora, dopo aver conseguito Abramo nostro padre secondo la carne?&#8221;<\/span> (Romani 4.1).<\/p>\n<p>Il termine \u00e8 usato nel senso di discendenti, perch\u00e9 secondo la carne Abramo \u00e8 il padre degli ebrei (Giovanni 8:37).<\/p>\n<p>L&#8217;apostolo delle genti dimostra che Abramo non ottenne nulla secondo la legge, poich\u00e9 se non fosse stato per la promessa che sarebbe stato erede del mondo, quando avrebbe ricevuto il sigillo della giustizia della fede nell&#8217;incirconcisione, non sarebbe il padre di tutti coloro che credono. (Romani 4: 10-13).<\/p>\n<p>Se non fosse per la parola di Dio data liberamente ad Abramo, sarebbe come gli altri uomini. Ma attraverso la parola di fede, Abramo credeva, la sua fede nella parola di Dio era la causa della giustificazione.<\/p>\n<p style=\"padding-left: 40px\"><span style=\"color: #0000ff\">\u201cPoi lo port\u00f2 fuori e disse: Guarda ora i cieli e conta le stelle, se puoi contarle. E gli disse: Cos\u00ec sar\u00e0 il tuo seme. E credette al Signore, e lo cont\u00f2 per la giustizia \u201d<\/span> (Genesi 15: 5-6).<\/p>\n<p>La connotazione del termine &#8220;carne&#8221; \u00e8 pi\u00f9 complessa nel capitolo 6:<\/p>\n<p style=\"padding-left: 40px\"><span style=\"color: #0000ff\">\u201cParlo come un uomo a causa della debolezza della tua carne; poich\u00e9 come hai presentato i tuoi membri per servire la sporcizia e il male alla malvagit\u00e0, cos\u00ec ora presenta i tuoi membri per servire la giustizia per la santificazione \u201d<\/span> (Romani 6:19).<\/p>\n<p>L&#8217;apostolo invoca l&#8217;istituto della schiavit\u00f9 per dimostrare la condizione dell&#8217;uomo sotto il peccato e la giustizia, e quindi sottolinea la necessit\u00e0 di argomentazioni: parlo come un uomo a causa della fragilit\u00e0 della carne degli interlocutori.<\/p>\n<p style=\"text-align: center\"><span style=\"color: #0000ff\">\u201c\u0391\u03bd\u03b8\u03c1\u03c9\u03c0\u03b9\u03bd\u03bf\u03bd \u03bb\u03b5\u03b3\u03c9 \u03b4\u03b9\u03b1 \u03c4\u03b7\u03bd \u03b1\u03c3\u03b8\u03b5\u03bd\u03b5\u03b9\u03b1\u03bd \u03c4\u03b7\u03c2 \u03c3\u03b1\u03c1\u03ba\u03bf\u03c2 \u03c5\u03bc\u03c9\u03bd\u201d <\/span>Scrivener\u2019s Textus Receptus (1894).<\/p>\n<p style=\"text-align: center\"><span style=\"color: #0000ff\">&#8220;In termini umani parlo a causa della debolezza <a style=\"color: #0000ff\" href=\"#_ftn3\" name=\"_ftnref3\">[3]<\/a> della tua carne&#8221;<\/span> New Greek Greek Interlinear New Testament, SBB.<\/p>\n<p>Il pronome possessivo \u1f51\u03bc\u1ff6\u03bd \u00e8 nel genitivo, e viene in seconda persona plurale per dimostrare la fragilit\u00e0 della carne degli interlocutori. L&#8217;apostolo si riferiva al corpo fatto di materia organica? Ai desideri e ai desideri umani? Le domande come l&#8217;etica e il carattere morale? No! L&#8217;apostolo stava sottolineando quanto fragile fosse l&#8217;argomento umano basato sull&#8217;essere disceso dalla carne di Abramo.<\/p>\n<p>L&#8217;argomentazione fatta dall&#8217;apostolo Paolo era comune per gli ebrei da presentare di fronte al Vangelo:<\/p>\n<p>Gli risposero: Siamo il seme di Abramo e non serviamo mai alcun uomo; come dici, sarai liberato? \u201d (Giovanni 8:33), oppure;<\/p>\n<p style=\"padding-left: 40px\">&#8220;Gli risposero e gli dissero: Abramo \u00e8 nostro padre&#8221; (Giovanni 8:39).<\/p>\n<p>La fragilit\u00e0 nel commento dice di coloro che hanno fatto della carne la loro salvezza, cio\u00e8 la loro forza:<\/p>\n<p style=\"padding-left: 40px\"><span style=\"color: #0000ff\">&#8220;Cos\u00ec dice l&#8217;Eterno: Maledetto \u00e8 l&#8217;uomo che confida nell&#8217;uomo, e fa carne sul suo braccio e allontana il suo cuore dall&#8217;Eterno!&#8221; <\/span>(Geremia 17: 5).<\/p>\n<p>In questo senso, il termine &#8220;carne&#8221; evidenziava l&#8217;essenza della dottrina ebraica, le letture erronee delle esposizioni paoline, alleate del pensiero filosofico greco, nacquero nel docetismo.<\/p>\n<p>Il docetismo, un flusso di pensiero eretico in cui il corpo di Ges\u00f9 Cristo era solo un&#8217;illusione e la sua crocifissione sarebbe stata solo apparente, poich\u00e9 avevano capito che la materia organica era essenzialmente corrotta.<\/p>\n<p>Il docetismo deriva da una certa corrente gnostica che crede che il mondo materiale sia malvagio e corrotto e, per cercare di conciliare la Scrittura con la filosofia greca, affermarono che Ges\u00f9 era uno spettro dall&#8217;aspetto umano, ma senza carne e sangue.<\/p>\n<p style=\"padding-left: 40px\"><span style=\"color: #0000ff\">\u201cPoich\u00e9 molti ingannatori sono venuti nel mondo che non confessano che Ges\u00f9 Cristo venne nella carne. Questo \u00e8 l&#8217;ingannatore e l&#8217;anticristo. \u201d<\/span> (2 Giovanni 1,7).<\/p>\n<p>Il prossimo uso del termine &#8220;carne&#8221; si trova nel capitolo 7:<\/p>\n<p style=\"padding-left: 40px\"><span style=\"color: #0000ff\">&#8220;Perch\u00e9 quando eravamo nella carne, le passioni dei peccati, che sono secondo la legge, esercitavano i nostri membri per produrre frutti fino alla morte&#8221;<\/span> (Romani 7.5).<\/p>\n<p>In questo versetto, l&#8217;apostolo Paolo usa il termine &#8220;carne&#8221; per nominare la dottrina ebraica, dimostrando che in passato sia lui che i suoi interlocutori erano nella carne. Inoltre, l&#8217;apostolo Paolo sottolinea categoricamente che i cristiani non erano pi\u00f9 nella carne ma nello spirito:<\/p>\n<p style=\"padding-left: 40px\"><span style=\"color: #0000ff\">\u201cMa tu non sei nella carne, ma nello Spirito, se lo Spirito di Dio abita in te. Ma se qualcuno non ha lo Spirito di Cristo, non \u00e8 suo \u201d<\/span>\u00a0(Romani 8.9).<\/p>\n<p>L&#8217;enfasi dell&#8217;apostolo dei gentili era sui cristiani convertiti tra gli ebrei, a differenza dell&#8217;approccio ai cristiani delle regioni della Galazia, che divenne tra i gentili:<\/p>\n<p style=\"padding-left: 40px\"><span style=\"color: #0000ff\">\u201cVolevo solo sapere questo da te: hai ricevuto lo Spirito dalle opere della legge o dalla predicazione della fede? Sei cos\u00ec sciocco che, a partire dallo Spirito, ora finisci con la carne?\u201d<\/span> (Galati 3: 2-3).<\/p>\n<p>Mentre i cristiani galati avevano iniziato a servire Dio secondo il vangelo (spirito), ora, a causa di un fascino (Galati 3: 1), si stavano avvicinando alla dottrina giudaizzante (carne).<\/p>\n<p>Il cristiano serve Dio nella novit\u00e0 della mente, non attraverso la vecchiaia della lettera (Rom. 7: 7). Il &#8220;vangelo&#8221; \u00e8 contrario alla &#8220;legge&#8221;, cos\u00ec come, rispettivamente, la &#8220;novit\u00e0 della mente&#8221; contesta &#8220;la vecchiaia della lettera&#8221;, o &#8220;la predicazione della fede&#8221; si oppone alle &#8220;opere della legge&#8221;, o lo &#8220;spirito&#8221; contrario alla &#8220;carne&#8221;.<\/p>\n<p>Passando al versetto 1 del capitolo 8 dell&#8217;Epistola ai Romani, \u00e8 certo che coloro che sono in Cristo sono nuove creature libere dalla condanna, poich\u00e9 non camminano secondo i precetti della legge, ma secondo la verit\u00e0 del Vangelo (spirito).<\/p>\n<p>La parola greca \u03c0\u03bd\u03b5\u1fe6\u03bc\u03b1 (pneuma), tradotta dallo spirito, in questo contesto si riferisce al vangelo di Cristo. Per questa verit\u00e0, l&#8217;apostolo Paolo dichiar\u00f2 di essere ministro di un Nuovo Testamento, cio\u00e8 dello spirito.<\/p>\n<p style=\"padding-left: 40px\"><span style=\"color: #0000ff\">\u201cChi ci ha anche reso capaci di essere ministri di un nuovo testamento, non della lettera, ma dello spirito; perch\u00e9 la lettera uccide e lo spirito d\u00e0 vita. \u201d<\/span> (2 Corinti 3: 6).<\/p>\n<p>Il versetto di cui sopra evidenzia l&#8217;opposizione &#8220;spirito&#8221; e &#8220;lettera&#8221;, presentando lo spirito come il Nuovo Testamento e la legge come la lettera, perch\u00e9 era incastonata nella pietra (2 Corinzi 3: 7). La legge \u00e8 presentata come il ministero della morte, che si oppone al vangelo, che \u00e8 il ministero dello spirito (2 Corinzi 3: 7-8).<\/p>\n<p>Da qui l&#8217;opposizione &#8220;spirito&#8221; e &#8220;lettera&#8221;, poich\u00e9 il Vangelo accelera mentre la legge uccide.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> <span style=\"color: #800080\"><em>\u201c3563 \u03bd\u03bf\u03c5\u03c2 probabilmente dalla radice del 1097; TDNT &#8211; 4: 951.636; 1) mente, comprese anche le facolt\u00e0 di percepire e comprendere, nonch\u00e9 la capacit\u00e0 di percepire, giudicare, determinare 1a) facolt\u00e0 mentali, comprendere 1b) ragionare nel senso pi\u00f9 stretto, come la capacit\u00e0 di verit\u00e0 spirituale, i poteri superiori dell&#8217;anima, la facolt\u00e0 di percepire le cose divine, di riconoscere la bont\u00e0 e di odiare il male 1c) il potere di meditare e giudicare in modo sobrio, calmo e imparziale 2) un modo particolare di pensare e giudicare, cio\u00e8 pensieri, sentimenti, scopi, desideri Sinonimi vedere la voce 5917 \u201d<\/em><\/span> Strong Bible Dictionary.<\/p>\n<p><a href=\"#_ftnref2\" name=\"_ftn2\">[2]<\/a> <span style=\"color: #800080\"><em>\u201c3551 \u03bd\u03bf\u03bc\u03bf\u03c2 nomi della parola primaria nemo (pacco, in particolare cibo o pascolo animale); TDNT &#8211; 4: 1022.646; 1) qualsiasi cosa stabilita, qualsiasi cosa ricevuta dall&#8217;uso, dall&#8217;usanza, dalla legge, dal comando 1a) di qualsiasi legge 1a1) una legge o una regola che produce uno stato approvato da Dio 1a1a) dall&#8217;osservanza di ci\u00f2 che \u00e8 approvato da Dio 1a2) un precetto o ingiunzione 1a3) la regola di azione prescritta dalla ragione 1b) della legge mosaica e riferendosi, in base al contesto, al volume della legge o al suo contenuto 1c) alla religione cristiana: la legge che richiede la fede, l&#8217;istruzione morale dato da Cristo, esp. love precept 1d) il nome della parte pi\u00f9 importante (il Pentateuco) \u00e8 usato per la raccolta completa dei libri sacri del Sinonimi AT vedi voce 5918 \u201d<\/em><\/span> Bible Dictionary Strong.<\/p>\n<p><a href=\"#_ftnref3\" name=\"_ftn3\">[3]<\/a> <span style=\"color: #800080\"><em>\u201c769 \u03b1\u03c3\u03b8 \u03b5\u03bd \u03b5\u03b9\u03b1 asteneneia di 772; TDNT &#8211; 1: 490,83; nf 1) mancanza di forza, debolezza, debolezza 1a) del corpo 1a1) sua naturale debolezza e debolezza 1a2) debolezza o malattia della salute 1b) dell&#8217;anima 1b1) mancanza di forza e capacit\u00e0 richiesta a 1b1a) di capire qualcosa 1b1b) di fare grandi cose e glorioso 1b1c) sopprime i desideri corrotti 1b1d) sopporta afflizioni e preoccupazioni \u201d<\/em><\/span> Strong Bible Dictionary.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entrambi i versetti hanno contrappunti: la &#8220;novit\u00e0 della mente&#8221; contrasta la &#8220;vecchiaia della lettera&#8221;, cos\u00ec come la &#8220;comprensione&#8221; contrasta la &#8220;carne&#8221;.<\/p>\n","protected":false},"author":1,"featured_media":110,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[37,58,64],"class_list":["post-109","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-giustificazione","tag-lettera","tag-romani-8","tag-spirito"],"acf":[],"_links":{"self":[{"href":"https:\/\/estudobiblico.org\/it\/wp-json\/wp\/v2\/posts\/109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/estudobiblico.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/estudobiblico.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/estudobiblico.org\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/estudobiblico.org\/it\/wp-json\/wp\/v2\/comments?post=109"}],"version-history":[{"count":0,"href":"https:\/\/estudobiblico.org\/it\/wp-json\/wp\/v2\/posts\/109\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/estudobiblico.org\/it\/wp-json\/wp\/v2\/media\/110"}],"wp:attachment":[{"href":"https:\/\/estudobiblico.org\/it\/wp-json\/wp\/v2\/media?parent=109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/estudobiblico.org\/it\/wp-json\/wp\/v2\/categories?post=109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/estudobiblico.org\/it\/wp-json\/wp\/v2\/tags?post=109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}